{"id":12256,"date":"2022-06-14T09:46:03","date_gmt":"2022-06-14T08:46:03","guid":{"rendered":"https:\/\/www.burrensmokehouse.com\/le-burren\/"},"modified":"2022-07-07T16:15:16","modified_gmt":"2022-07-07T15:15:16","slug":"le-burren","status":"publish","type":"post","link":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/","title":{"rendered":"Le Burren"},"content":{"rendered":"<h2>Un paysage unique<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10738\" src=\"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398.jpg\" alt=\"\" width=\"1920\" height=\"847\" srcset=\"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398.jpg 1920w, https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-300x132.jpg 300w, https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-1024x452.jpg 1024w, https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-768x339.jpg 768w, https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-60x26.jpg 60w, https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-110x49.jpg 110w, https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-1536x678.jpg 1536w, https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-600x265.jpg 600w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<h5><strong>Qu&rsquo;est-ce que le Burren ?<\/strong><\/h5>\n<p><span style=\"font-weight: 400;\">Le Burren est un paysage karstique o\u00f9 le calcaire a \u00e9t\u00e9 expos\u00e9 par l&rsquo;intervention humaine. Il y a environ 6 000 ans, les premiers colons permanents ont d\u00e9gag\u00e9 les collines des arbres pour le bois de chauffage et pour faire pousser des cultures. Cela a conduit \u00e0 l&rsquo;\u00e9rosion et le sol fertile s&rsquo;est accumul\u00e9 dans la vall\u00e9e.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un nouvel \u00e9cosyst\u00e8me a \u00e9volu\u00e9. Des plantes rares de l&rsquo;Arctique, des Alpes et de la M\u00e9diterran\u00e9e ont commenc\u00e9 \u00e0 pousser ici. C&rsquo;est un spectacle \u00e9tonnant quand les orchid\u00e9es de la M\u00e9diterran\u00e9e, les beno\u00eetes de montagne de l&rsquo;Arctique et les gentianes des Alpes poussent ensemble au m\u00eame endroit. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le Burren est appel\u00e9 le Rocher Fertile. Il peut sembler nu lorsque vous le traversez, mais une fois que vous sortez de la voiture et marchez sur le pav\u00e9 calcaire, vous pouvez voir la grande biodiversit\u00e9 et la beaut\u00e9 des fleurs partout. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">C&rsquo;est une r\u00e9gion avec la plus forte concentration de puits sacr\u00e9s en Irlande. De nombreux monuments anciens comme les forts circulaires, les tumulus et les dolmens se trouvent ici. C&rsquo;est aussi un paradis pour les sp\u00e9l\u00e9ologues en raison de l&rsquo;\u00e9norme quantit\u00e9 de grottes. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Marcher sur les sentiers d\u00e9sign\u00e9s du Burren \u00e0 travers les vall\u00e9es et les collines est un passe-temps favori des habitants et des touristes qui aiment profiter de la vue sur les collines calcaires et la mer. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous pouvez en savoir plus sur le Burren sur le site Web de <a href=\"https:\/\/burrenbeo.com\/\" target=\"_blank\" rel=\"noopener\">Burrenbeo et sur le site Web<\/a> du <a href=\"https:\/\/www.burrengeopark.ie\/\" target=\"_blank\" rel=\"noopener\">Burren &amp; Cliffs of Moher Geopark<\/a> . <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un paysage unique Qu&rsquo;est-ce que le Burren ? Le Burren est un paysage karstique o\u00f9 le calcaire a \u00e9t\u00e9 expos\u00e9 par l&rsquo;intervention humaine. Il y a environ 6 000 ans, les premiers colons permanents ont d\u00e9gag\u00e9 les collines des arbres pour le bois de chauffage et pour faire pousser des cultures. Cela a conduit \u00e0 [&hellip;]<\/p>\n","protected":false},"author":4603,"featured_media":11214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"categories":[99],"tags":[],"class_list":["post-12256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Burren - Burren Smokehouse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Burren - Burren Smokehouse\" \/>\n<meta property=\"og:description\" content=\"Un paysage unique Qu&rsquo;est-ce que le Burren ? Le Burren est un paysage karstique o\u00f9 le calcaire a \u00e9t\u00e9 expos\u00e9 par l&rsquo;intervention humaine. Il y a environ 6 000 ans, les premiers colons permanents ont d\u00e9gag\u00e9 les collines des arbres pour le bois de chauffage et pour faire pousser des cultures. Cela a conduit \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/\" \/>\n<meta property=\"og:site_name\" content=\"Burren Smokehouse\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-14T08:46:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-07T15:15:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/\"},\"author\":{\"name\":\"Karin\",\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/#\\\/schema\\\/person\\\/81fb6322d966444a16b24f9b9544ddc0\"},\"headline\":\"Le Burren\",\"datePublished\":\"2022-06-14T08:46:03+00:00\",\"dateModified\":\"2022-07-07T15:15:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/\"},\"wordCount\":274,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/burrensmokehouse-1398-1.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/\",\"url\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/\",\"name\":\"Le Burren - Burren Smokehouse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/burrensmokehouse-1398-1.jpg\",\"datePublished\":\"2022-06-14T08:46:03+00:00\",\"dateModified\":\"2022-07-07T15:15:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/burrensmokehouse-1398-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/burrensmokehouse-1398-1.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/le-burren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Burren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/\",\"name\":\"Burren Smokehouse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/#organization\",\"name\":\"Burren Smokehouse\",\"url\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo.png\",\"width\":432,\"height\":99,\"caption\":\"Burren Smokehouse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/#\\\/schema\\\/person\\\/81fb6322d966444a16b24f9b9544ddc0\",\"name\":\"Karin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e84f7e896dd01ac7cf6d3ef1885921063d4ba55b521465e26ff9af4a116d3648?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e84f7e896dd01ac7cf6d3ef1885921063d4ba55b521465e26ff9af4a116d3648?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e84f7e896dd01ac7cf6d3ef1885921063d4ba55b521465e26ff9af4a116d3648?s=96&d=blank&r=g\",\"caption\":\"Karin\"},\"url\":\"https:\\\/\\\/www.burrensmokehouse.com\\\/fr\\\/author\\\/karin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Burren - Burren Smokehouse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Burren - Burren Smokehouse","og_description":"Un paysage unique Qu&rsquo;est-ce que le Burren ? Le Burren est un paysage karstique o\u00f9 le calcaire a \u00e9t\u00e9 expos\u00e9 par l&rsquo;intervention humaine. Il y a environ 6 000 ans, les premiers colons permanents ont d\u00e9gag\u00e9 les collines des arbres pour le bois de chauffage et pour faire pousser des cultures. Cela a conduit \u00e0 [&hellip;]","og_url":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/","og_site_name":"Burren Smokehouse","article_published_time":"2022-06-14T08:46:03+00:00","article_modified_time":"2022-07-07T15:15:16+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-1.jpg","type":"image\/jpeg"}],"author":"Karin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Karin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/#article","isPartOf":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/"},"author":{"name":"Karin","@id":"https:\/\/www.burrensmokehouse.com\/fr\/#\/schema\/person\/81fb6322d966444a16b24f9b9544ddc0"},"headline":"Le Burren","datePublished":"2022-06-14T08:46:03+00:00","dateModified":"2022-07-07T15:15:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/"},"wordCount":274,"commentCount":0,"publisher":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-1.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/","url":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/","name":"Le Burren - Burren Smokehouse","isPartOf":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/#primaryimage"},"image":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-1.jpg","datePublished":"2022-06-14T08:46:03+00:00","dateModified":"2022-07-07T15:15:16+00:00","breadcrumb":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/#primaryimage","url":"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-1.jpg","contentUrl":"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2022\/05\/burrensmokehouse-1398-1.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.burrensmokehouse.com\/fr\/le-burren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.burrensmokehouse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Burren"}]},{"@type":"WebSite","@id":"https:\/\/www.burrensmokehouse.com\/fr\/#website","url":"https:\/\/www.burrensmokehouse.com\/fr\/","name":"Burren Smokehouse","description":"","publisher":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.burrensmokehouse.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.burrensmokehouse.com\/fr\/#organization","name":"Burren Smokehouse","url":"https:\/\/www.burrensmokehouse.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.burrensmokehouse.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2021\/07\/logo.png","contentUrl":"https:\/\/www.burrensmokehouse.com\/wp-content\/uploads\/2021\/07\/logo.png","width":432,"height":99,"caption":"Burren Smokehouse"},"image":{"@id":"https:\/\/www.burrensmokehouse.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.burrensmokehouse.com\/fr\/#\/schema\/person\/81fb6322d966444a16b24f9b9544ddc0","name":"Karin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e84f7e896dd01ac7cf6d3ef1885921063d4ba55b521465e26ff9af4a116d3648?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e84f7e896dd01ac7cf6d3ef1885921063d4ba55b521465e26ff9af4a116d3648?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e84f7e896dd01ac7cf6d3ef1885921063d4ba55b521465e26ff9af4a116d3648?s=96&d=blank&r=g","caption":"Karin"},"url":"https:\/\/www.burrensmokehouse.com\/fr\/author\/karin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/posts\/12256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/users\/4603"}],"replies":[{"embeddable":true,"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/comments?post=12256"}],"version-history":[{"count":0,"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/posts\/12256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/media\/11214"}],"wp:attachment":[{"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/media?parent=12256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/categories?post=12256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.burrensmokehouse.com\/fr\/wp-json\/wp\/v2\/tags?post=12256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}